{"id":524,"date":"2025-05-31T23:51:43","date_gmt":"2025-05-31T23:51:43","guid":{"rendered":"https:\/\/fatecbarueri.edu.br\/home\/?page_id=524"},"modified":"2025-07-15T15:49:01","modified_gmt":"2025-07-15T15:49:01","slug":"expedicao-de-certificados","status":"publish","type":"page","link":"https:\/\/fatecbarueri.edu.br\/home\/expedicao-de-certificados\/","title":{"rendered":"Expedi\u00e7\u00e3o de Certificados"},"content":{"rendered":"\n<p>Os diplomas dos alunos formados s\u00e3o confeccionados pelo Centro Paula Souza. <\/p>\n\n\n\n<p>Nesse sentido, a Secretaria Acad\u00eamica da Fatec Barueri atua diligentemente para envio dos processos de expedi\u00e7\u00e3o dos diplomas ao CPS imediatamente ap\u00f3s a cola\u00e7\u00e3o de grau.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Os diplomas dos alunos formados s\u00e3o confeccionados pelo Centro Paula Souza. Nesse sentido, a Secretaria Acad\u00eamica da Fatec Barueri atua diligentemente para envio dos processos de expedi\u00e7\u00e3o dos diplomas ao CPS imediatamente ap\u00f3s a cola\u00e7\u00e3o de grau.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-no-sidebar.php","meta":{"footnotes":""},"class_list":["post-524","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fatecbarueri.edu.br\/home\/wp-json\/wp\/v2\/pages\/524"}],"collection":[{"href":"https:\/\/fatecbarueri.edu.br\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fatecbarueri.edu.br\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fatecbarueri.edu.br\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fatecbarueri.edu.br\/home\/wp-json\/wp\/v2\/comments?post=524"}],"version-history":[{"count":2,"href":"https:\/\/fatecbarueri.edu.br\/home\/wp-json\/wp\/v2\/pages\/524\/revisions"}],"predecessor-version":[{"id":958,"href":"https:\/\/fatecbarueri.edu.br\/home\/wp-json\/wp\/v2\/pages\/524\/revisions\/958"}],"wp:attachment":[{"href":"https:\/\/fatecbarueri.edu.br\/home\/wp-json\/wp\/v2\/media?parent=524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}